{"id":2547,"date":"2024-10-09T09:15:21","date_gmt":"2024-10-09T07:15:21","guid":{"rendered":"https:\/\/ellistat.com\/?post_type=guide-dutilisateur&#038;p=2547"},"modified":"2024-10-23T16:48:56","modified_gmt":"2024-10-23T14:48:56","slug":"02-anteil","status":"publish","type":"guide-dutilisateur","link":"https:\/\/ellistat.com\/de\/guide-dutilisateur\/02-proportion\/","title":{"rendered":"Proportionen"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Ellistat <a href=\"https:\/\/ellistat.com\/de\/solutions-data-analysis\/\">Datenanalyse <\/a>bietet eine ganze Reihe von statistischen Tests zum Vergleich von Anteilen an. Hierf\u00fcr stehen drei Haupttests zur Verf\u00fcgung:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"995\" height=\"446\" src=\"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-38.png\" alt=\"\" class=\"wp-image-2548\" srcset=\"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-38.png 995w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-38-300x134.png 300w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-38-768x344.png 768w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-38-18x8.png 18w\" sizes=\"auto, (max-width: 995px) 100vw, 995px\" \/><\/figure>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Einfacher Proportionstest (1P): Ideal f\u00fcr den Vergleich eines Anteils mit einem Referenzwert oder einer bestimmten Hypothese.<\/li>\n\n\n\n<li>Proportionstest (2P): N\u00fctzlich, um zwei Proportionen miteinander zu vergleichen, wobei signifikante Unterschiede zwischen zwei Gruppen oder Populationen hervorgehoben werden.<\/li>\n\n\n\n<li>Chi2-Test f\u00fcr mehrere Proportionen : Geeignet, um die Anteile mehrerer Gruppen oder Kategorien gleichzeitig zu vergleichen, was eine robuste und detaillierte vergleichende Analyse erm\u00f6glicht.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Vergleich der Proportionen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Im Folgenden werden die von Ellistat Data Analysis angebotenen Proportionsvergleichsanalysen zusammengefasst. Nehmen wir als Beispiel die folgenden qualitativen Daten: <a href=\"https:\/\/www.notion.so\/Proportion-8167aea96fae4f58ab1f46cb85681912?pvs=21\">Anteil<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">An diesem Datensatz k\u00f6nnen mehrere Analysen durchgef\u00fchrt werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Beispiel: Einen 1P-Test durchf\u00fchren, um einen Anteil mit einem Referenzwert zu vergleichen.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um einen Anteil mit einem theoretischen Ziel zu vergleichen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"532\" src=\"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-39-1024x532.png\" alt=\"\" class=\"wp-image-2549\" srcset=\"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-39-1024x532.png 1024w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-39-300x156.png 300w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-39-768x399.png 768w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-39-1536x798.png 1536w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-39-18x9.png 18w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-39.png 1968w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Setzen Sie qualitative Daten mit zwei Modalit\u00e4ten in das Raster ein. (im obigen Beispiel 61C\/ 21NC).<\/li>\n\n\n\n<li>Klicken Sie auf das Men\u00fc \"Inferenzstatistiken\".<\/li>\n\n\n\n<li>In der&nbsp;<strong>Zone 1<\/strong>W\u00e4hlen Sie in Y die Spalte mit den qualitativen Daten.<\/li>\n\n\n\n<li>In&nbsp;<strong>Zone 2,<\/strong>&nbsp;w\u00e4hlen Sie den Typ Ihrer Daten. Wenn Ihre Spalte qualitative Werte enth\u00e4lt, schl\u00e4gt Ellistat standardm\u00e4\u00dfig nur \"Anteil\" vor, wenn die Daten jedoch quantitativ sind, schl\u00e4gt Ellistat sowohl den Typ \"Anteil\" als auch den Typ \"Population\" vor. \ud83d\udcdd: W\u00e4hlen Sie \"Proportion\", wenn Sie einen 1P-, 2P- oder Chi-2-Test durchf\u00fchren und w\u00e4hlen Sie den Typ \"Proportion\".<\/li>\n\n\n\n<li>In&nbsp;<strong>Zone 3<\/strong>wird die in Feld 2 ausgew\u00e4hlte Grafik angezeigt.<\/li>\n\n\n\n<li>In der&nbsp;<strong>Zone 4<\/strong>Das Signifikanzergebnis (wird auf der rechten Seite angezeigt) mit den verschiedenen Statistiken darunter. (Die Abweichung zwischen dem Anteil und dem theoretischen Anteil ist signifikant, wenn der P-Wert kleiner als 0,05 ist, im n\u00e4chsten Fall kann man auf signifikant schlie\u00dfen). \ud83d\udcdd: Der Inhalt von&nbsp;<strong>Zone 4<\/strong>h\u00e4ngt vom gew\u00e4hlten Datentyp in&nbsp;<strong>Zone 2<\/strong>. Bei einem 1P-, 2P- oder Chi-2-Test w\u00e4hlen Sie den Typ \"Anteil\".<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"559\" height=\"314\" src=\"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-40.png\" alt=\"\" class=\"wp-image-2550\" srcset=\"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-40.png 559w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-40-300x169.png 300w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-40-18x10.png 18w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Beispiel: Einen 2P-Test durchf\u00fchren, um zwei Anteile P1 und P2 zu vergleichen.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um einen Vergleich der Anteile zweier Populationen durchzuf\u00fchren.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"529\" src=\"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-41-1024x529.png\" alt=\"\" class=\"wp-image-2551\" srcset=\"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-41-1024x529.png 1024w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-41-300x155.png 300w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-41-768x397.png 768w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-41-1536x794.png 1536w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-41-18x9.png 18w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-41.png 2009w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<ul class=\"wp-block-list\">\n<li>Setzen Sie qualitative Daten mit zwei Modalit\u00e4ten in eine Spalte des Rasters ein. (Im obigen Beispiel \"Compliance\": 61C\/ 21NC , \"Compliance 2\": 63C\/19NC).<\/li>\n\n\n\n<li>Klicken Sie auf das Men\u00fc \"Inferenzstatistiken\".<\/li>\n\n\n\n<li>In der&nbsp;<strong>Zone 1<\/strong>, w\u00e4hlen Sie in&nbsp;<strong>Y<\/strong>&nbsp;die beiden Spalten \"Compliance\" und \"Compliance 2\" mit den qualitativen Daten.<\/li>\n\n\n\n<li>In&nbsp;<strong>Zone 2,<\/strong>&nbsp;w\u00e4hlen Sie den Typ Ihrer Daten. Wenn Ihre Spalte qualitative Werte enth\u00e4lt, schl\u00e4gt Ellistat standardm\u00e4\u00dfig nur \"Anteil\" vor, wenn die Daten jedoch quantitativ sind, schl\u00e4gt Ellistat sowohl den Typ \"Anteil\" als auch den Typ \"Population\" vor. \ud83d\udcdd: W\u00e4hlen Sie \"Proportion\", wenn Sie einen 1P-, 2P- oder Chi-2-Test durchf\u00fchren und w\u00e4hlen Sie den Typ \"Proportion\".<\/li>\n\n\n\n<li>In&nbsp;<strong>Zone 3<\/strong>wird die in Feld 2 ausgew\u00e4hlte Grafik angezeigt.<\/li>\n\n\n\n<li>In der&nbsp;<strong>Zone 4<\/strong>Das Signifikanzergebnis (wird auf der rechten Seite angezeigt) mit den verschiedenen Statistiken darunter. (Die Abweichung zwischen dem Anteil und dem theoretischen Anteil ist signifikant, wenn der P-Wert kleiner als 0,05 ist, im n\u00e4chsten Fall kann man auf signifikant schlie\u00dfen). \ud83d\udcdd: Der Inhalt von&nbsp;<strong>Zone 4<\/strong>h\u00e4ngt vom gew\u00e4hlten Datentyp in&nbsp;<strong>Zone 2<\/strong>. Bei 1P-, 2P- oder Chi-2-Tests w\u00e4hlen Sie den Typ \"Anteil\" .<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Beispiel: F\u00fchren Sie einen Chi-Quadrat-Test durch, um die Anteile mehrerer Gruppen oder Kategorien gleichzeitig zu vergleichen.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um einen Vergleich der Anteile zweier Populationen durchzuf\u00fchren.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"529\" src=\"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-42-1024x529.png\" alt=\"\" class=\"wp-image-2552\" srcset=\"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-42-1024x529.png 1024w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-42-300x155.png 300w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-42-768x397.png 768w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-42-1536x794.png 1536w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-42-18x9.png 18w, https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-42.png 2009w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Setzen Sie qualitative Daten mit zwei Modalit\u00e4ten in eine Spalte des Rasters. (Im obigen Beispiel \"Compliance\": 61C\/ 21NC , \"Compliance 2\": 63C\/19NC und \"Compliance 3\": 38C \/44 NC).<\/li>\n\n\n\n<li>Klicken Sie auf das Men\u00fc \"Inferenzstatistiken\".<\/li>\n\n\n\n<li>In der&nbsp;<strong>Zone 1<\/strong>, w\u00e4hlen Sie in&nbsp;<strong>Y<\/strong>&nbsp;die 3 Spalten \"Compliance\", \"Compliance 2\" und \"Compliance 3\" mit den qualitativen Daten.<\/li>\n\n\n\n<li>In&nbsp;<strong>Zone 2,<\/strong>&nbsp;w\u00e4hlen Sie den Typ Ihrer Daten. Wenn Ihre Spalte qualitative Werte enth\u00e4lt, schl\u00e4gt Ellistat standardm\u00e4\u00dfig nur \"Anteil\" vor, wenn die Daten jedoch quantitativ sind, schl\u00e4gt Ellistat sowohl den Typ \"Anteil\" als auch den Typ \"Population\" vor. \ud83d\udcdd: W\u00e4hlen Sie \"Proportion\", wenn Sie einen 1P-, 2P- oder Chi-2-Test durchf\u00fchren und w\u00e4hlen Sie den Typ \"Proportion\".<\/li>\n\n\n\n<li>In&nbsp;<strong>Zone 3<\/strong>wird die ausgew\u00e4hlte Grafik in&nbsp;<strong>Zone 2<\/strong>.<\/li>\n\n\n\n<li>In der&nbsp;<strong>Zone 4<\/strong>Das Signifikanzergebnis (wird auf der rechten Seite angezeigt) mit den verschiedenen Statistiken darunter. (Die Abweichung zwischen dem Anteil und dem theoretischen Anteil ist signifikant, wenn der P-Wert kleiner als 0,05 ist, im n\u00e4chsten Fall kann man auf signifikant schlie\u00dfen). \ud83d\udcdd: Der Inhalt von&nbsp;<strong>Zone 4<\/strong>h\u00e4ngt vom gew\u00e4hlten Datentyp in&nbsp;<strong>Zone 2<\/strong>. Bei 1P-, 2P- oder Chi-2-Tests w\u00e4hlen Sie den Typ \"Anteil\" .<\/li>\n<\/ul>","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"menu-guide-dutilisateur":[23],"class_list":["post-2547","guide-dutilisateur","type-guide-dutilisateur","status-publish","hentry","menu-guide-dutilisateur-5-statistiques-inferentielles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proportions - Ellistat<\/title>\n<meta name=\"description\" content=\"Ellistat propose une gamme compl\u00e8te de tests statistiques pour comparer les proportions. Voici notre guide d&#039;utilisateur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ellistat.com\/de\/benutzerhandbuch\/02-anteil\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proportions - Ellistat\" \/>\n<meta property=\"og:description\" content=\"Ellistat propose une gamme compl\u00e8te de tests statistiques pour comparer les proportions. Voici notre guide d&#039;utilisateur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ellistat.com\/de\/benutzerhandbuch\/02-anteil\/\" \/>\n<meta property=\"og:site_name\" content=\"Ellistat\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-23T14:48:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-38.png\" \/>\n\t<meta property=\"og:image:width\" content=\"995\" \/>\n\t<meta property=\"og:image:height\" content=\"446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/02-proportion\\\/\",\"url\":\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/02-proportion\\\/\",\"name\":\"Proportions - Ellistat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/02-proportion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/02-proportion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/Untitled-38.png\",\"datePublished\":\"2024-10-09T07:15:21+00:00\",\"dateModified\":\"2024-10-23T14:48:56+00:00\",\"description\":\"Ellistat propose une gamme compl\u00e8te de tests statistiques pour comparer les proportions. Voici notre guide d'utilisateur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/02-proportion\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/02-proportion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/02-proportion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/Untitled-38.png\",\"contentUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/Untitled-38.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/02-proportion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ellistat.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proportions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/#website\",\"url\":\"https:\\\/\\\/ellistat.com\\\/\",\"name\":\"Ellistat\",\"description\":\"La suite qualit\u00e9 de l&#039;industrie m\u00e9canique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ellistat.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proportionen - Ellistat","description":"Ellistat bietet eine ganze Reihe von statistischen Tests zum Vergleich von Proportionen. Hier ist unser Benutzerleitfaden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ellistat.com\/de\/benutzerhandbuch\/02-anteil\/","og_locale":"de_DE","og_type":"article","og_title":"Proportions - Ellistat","og_description":"Ellistat propose une gamme compl\u00e8te de tests statistiques pour comparer les proportions. Voici notre guide d'utilisateur.","og_url":"https:\/\/ellistat.com\/de\/benutzerhandbuch\/02-anteil\/","og_site_name":"Ellistat","article_modified_time":"2024-10-23T14:48:56+00:00","og_image":[{"width":995,"height":446,"url":"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-38.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ellistat.com\/guide-dutilisateur\/02-proportion\/","url":"https:\/\/ellistat.com\/guide-dutilisateur\/02-proportion\/","name":"Proportionen - Ellistat","isPartOf":{"@id":"https:\/\/ellistat.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ellistat.com\/guide-dutilisateur\/02-proportion\/#primaryimage"},"image":{"@id":"https:\/\/ellistat.com\/guide-dutilisateur\/02-proportion\/#primaryimage"},"thumbnailUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-38.png","datePublished":"2024-10-09T07:15:21+00:00","dateModified":"2024-10-23T14:48:56+00:00","description":"Ellistat bietet eine ganze Reihe von statistischen Tests zum Vergleich von Proportionen. Hier ist unser Benutzerleitfaden.","breadcrumb":{"@id":"https:\/\/ellistat.com\/guide-dutilisateur\/02-proportion\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ellistat.com\/guide-dutilisateur\/02-proportion\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ellistat.com\/guide-dutilisateur\/02-proportion\/#primaryimage","url":"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-38.png","contentUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/Untitled-38.png"},{"@type":"BreadcrumbList","@id":"https:\/\/ellistat.com\/guide-dutilisateur\/02-proportion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ellistat.com\/"},{"@type":"ListItem","position":2,"name":"Proportions"}]},{"@type":"WebSite","@id":"https:\/\/ellistat.com\/#website","url":"https:\/\/ellistat.com\/","name":"Ellistat","description":"Die Qualit\u00e4tssuite der Maschinenbauindustrie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ellistat.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/guide-dutilisateur\/2547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/guide-dutilisateur"}],"about":[{"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/types\/guide-dutilisateur"}],"wp:attachment":[{"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/media?parent=2547"}],"wp:term":[{"taxonomy":"menu-guide-dutilisateur","embeddable":true,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/menu-guide-dutilisateur?post=2547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}