{"id":169,"date":"2024-08-08T09:21:09","date_gmt":"2024-08-08T07:21:09","guid":{"rendered":"https:\/\/site.ellistat.com\/?p=169"},"modified":"2024-10-23T14:52:17","modified_gmt":"2024-10-23T12:52:17","slug":"ellistat-kundigt-umfassende-qualitatssoftware-suite-an","status":"publish","type":"post","link":"https:\/\/ellistat.com\/de\/ellistat-annonce-une-suite-logicielle-qualite-complete\/","title":{"rendered":"Ellistats Qualit\u00e4tssoftware-Suite"},"content":{"rendered":"<p><strong>Ellistat, ein Softwareunternehmen, das f\u00fcr seine APC-Softwarel\u00f6sung zur Automatisierung der Einstellung von Werkzeugmaschinen bekannt ist, bringt ein neues, umfassendes Softwareangebot f\u00fcr die Qualit\u00e4t in der Produktion auf den Markt. Diese modulare, innovative, intuitive und 100% Web-basierte Qualit\u00e4tssuite ist das Ergebnis einer Strategie und von Entwicklungen, die seit der Gr\u00fcndung des Unternehmens umgesetzt wurden. Von nun an positioniert sich Ellistat nicht mehr nur als Experte im Bereich der maschinellen Bearbeitung, sondern im weiteren Sinne als Experte f\u00fcr industrielle Qualit\u00e4t. Die Ellistat-Software-Suite wird vorab vorgestellt<\/strong><strong>\u00e4ische Kommission<\/strong><strong>&nbsp;Welt, auf der Global Industrie Paris 2024.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading h3\">Von der Qualit\u00e4tsberatung bis zur Softwareentwicklung<\/h2>\n\n\n\n<p>Bisher beruhte der Erfolg des franz\u00f6sischen Unternehmens Ellistat auf seiner Expertise in der Qualit\u00e4tsschulung\/-beratung in Lean, Six Sigma. Aber auch auf seiner Flaggschiff-Software APC (Automated Process Control). Zahlreiche Hersteller und Zulieferer (Medizintechnik, Automobilindustrie, Luft- und Raumfahrt, Uhrenindustrie usw.) haben sich f\u00fcr diese revolution\u00e4re, extrem einfach zu bedienende Technologie entschieden. APC wurde mehrfach auf Industriemessen mit Troph\u00e4en ausgezeichnet und automatisiert den Einstellungsprozess von Werkzeugmaschinen, um vom ersten bearbeiteten Werkst\u00fcck an eine konforme Qualit\u00e4t zu erzielen.<\/p>\n\n\n\n<p>Heute entwickelt sich Ellistat weiter und bietet ein komplettes Softwarepaket an. Sie besteht aus verschiedenen autonomen Modulen, die untereinander kommunizieren. Es handelt sich um DIE Qualit\u00e4tssuite auf dem Markt, die der industriellen Qualit\u00e4t gewidmet ist und von Qualit\u00e4tsexperten entwickelt wurde. Die Entwicklungen dieser Suite begannen vor mehr als zehn Jahren. Sie wurde von Maurice Pillet*, dem Vater des Gr\u00fcnders von Ellistat, initiiert, der als eine der franz\u00f6sischen Referenzen f\u00fcr Qualit\u00e4t in der Produktion bekannt ist. Maurice hat im Laufe seiner Karriere zahlreiche B\u00fccher \u00fcber die Erfahrungsplanung, die Prozesssteuerung und Six Sigma ver\u00f6ffentlicht. Eines davon,&nbsp;<a href=\"https:\/\/www.eyrolles.com\/Entreprise\/Livre\/six-sigma-9782212557107\/\">\"Six Sigma - Wie man es anwendet\"&nbsp;<\/a>ist insbesondere zum Standardwerk in diesem Bereich geworden.<\/p>\n\n\n\n<p>Davy Pillet, CEO von Ellistat: \"Wir freuen uns, den Industrieunternehmen unsere Quality Suite vorstellen zu k\u00f6nnen. Im Rahmen ihrer Digitalisierungsstrategie zielt Ellistat darauf ab, ihre betriebliche Effizienz zu steigern, ihre Produktionsprozesse zu optimieren, die Einhaltung von Normen und Vorschriften zu gew\u00e4hrleisten, ihre Produktionskosten zu senken und schlie\u00dflich die Qualit\u00e4t ihrer Produkte zu verbessern.&nbsp;<\/p>\n\n\n\n<p>Mit dem Angebot dieser Suite Qualit\u00e9 will Ellistat einem historischen Markt einen neuen Anstrich verleihen.  \"Wir glauben, dass es noch Raum f\u00fcr Innovationen gibt\", gesteht Davy Pillet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Eine umfassende Qualit\u00e4tssoftware-Suite, die sich auf die Optimierung der Investitionsrendite konzentriert...<\/h2>\n\n\n\n<p>Ellistat ist mittlerweile in seiner Entwicklung ausgereift und bietet eine komplette Software-Suite rund um die industrielle Qualit\u00e4t an. Es enth\u00e4lt alle Standardfunktionen, die traditionell angeboten werden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/ellistat.com\/de\/solutions-spc\/\"><strong>SPC (Statistical Process Control)<\/strong><\/a>&nbsp;: erm\u00f6glicht es, die statistische Entwicklung der Prozesse zu verfolgen und die Produktion in Echtzeit zu steuern.<\/li>\n\n\n\n<li><a href=\"https:\/\/ellistat.com\/de\/solutions-iqc\/\"><strong>IQC (Incoming Quality Control)<\/strong><\/a>&nbsp;:erm\u00f6glicht die Kontrolle von Lieferantenmustern. Dank der Funktionen Dynamisierung und progressive Kontrolle ist es nun m\u00f6glich, die Anzahl der durchgef\u00fchrten Kontrollen f\u00fcr dieselbe eingehende Qualit\u00e4t um die H\u00e4lfte zu reduzieren.<\/li>\n\n\n\n<li><a href=\"https:\/\/ellistat.com\/de\/metro\/\"><strong>METRO<\/strong>&nbsp;<\/a>: erm\u00f6glicht es, die Konformit\u00e4t von Kontrollinstrumenten sicherzustellen. Indem nicht nur ihre Kalibrierungen, sondern auch die damit verbundenen R&amp;R-Gagen verfolgt werden. Das Modul METRO bietet einen effizienten und automatisierten Ansatz zur Aufrechterhaltung der Genauigkeit von Messinstrumenten. Om erm\u00f6glicht so die Sicherstellung der Produktqualit\u00e4t und der Einhaltung von Normen und Vorschriften.<\/li>\n\n\n\n<li><strong>NON-CONFORMITIES<\/strong>&nbsp;: erm\u00f6glicht es, Vorf\u00e4lle von Nichtkonformit\u00e4t effektiv zu erkennen, zu verfolgen und zu beheben. Das Modul NON-CONFORMITIES verbessert die Reaktionsf\u00e4higkeit, R\u00fcckverfolgbarkeit, Effizienz und Pr\u00e4vention von Qualit\u00e4tsproblemen. Es tr\u00e4gt somit zur Steigerung der Kundenzufriedenheit und zur Einhaltung gesetzlicher Vorschriften bei.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">...mit neuen Funktionen<\/h2>\n\n\n\n<p>Ellistat bietet nicht nur einen innovativen Benutzer- und Technikansatz f\u00fcr die sogenannten \"Standard\"-Funktionen, sondern auch neuartige Zusatzmodule:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/ellistat.com\/de\/solutions-data-analysis\/\"><strong>DATA ANALYSIS<\/strong><\/a>Das Modul Data Analysis: erm\u00f6glicht die Berechnung von Wahrscheinlichkeiten, die Erstellung eines Versuchsplans... Aber auch die statistische Analyse von Daten aus den Modulen SPC und IQC. Das Modul Data Analysis zeichnet sich durch seine Funktionsvielfalt aus. Seine Machine-Learning-Algorithmen erm\u00f6glichen es, den Ursprung der Drift einer Maschine zu verstehen oder Lieferanten statistisch zu differenzieren.<\/li>\n\n\n\n<li><a href=\"https:\/\/ellistat.com\/de\/e-learning-losungen\/\"><strong>E-LEARNING<\/strong><\/a>: 70 Schulungsmodule, um alle Mitarbeiter in den Werkzeugen von Lean und Qualit\u00e4t zu schulen und die Kompetenz des gesamten Unternehmens zu steigern.<\/li>\n\n\n\n<li><a href=\"https:\/\/ellistat.com\/de\/solutions-apc\/\"><strong>APC (Automated Process Control)<\/strong><\/a>Dieses Modul erm\u00f6glicht die Automatisierung des Einrichtungsprozesses von Werkzeugmaschinen, um die Qualit\u00e4t des ersten bearbeiteten Werkst\u00fccks zu gew\u00e4hrleisten.<\/li>\n<\/ul>\n\n\n\n<p>Davy Pillet kommentiert: \"&nbsp;<em>Bei der Entwicklung der Ellistat Quality Software Suite wurde der Schwerpunkt auf die Maximierung des Return on Investment gelegt. Die Idee ist zum Beispiel, zu sehen, inwieweit es m\u00f6glich ist, die Anzahl der Kontrollen bei gleicher Qualit\u00e4t zu reduzieren. Oder mit dem SPC-Modul, das mit dem Data Analysis-Modul verbunden ist, Daten zu erhalten, aber vor allem, sie nutzen zu k\u00f6nnen, um herauszufinden, woher das Problem kommt, und dann in der Lage zu sein, die richtigen Entscheidungen zu treffen.\"<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Einfache Anwendung und Implementierung f\u00fcr Ellistats Qualit\u00e4tssoftware-Suite<\/h2>\n\n\n\n<p>Die L\u00f6sung basiert auf einer nativen \"Full Web\"-Architektur. Der offensichtlichste Vorteil dieser Architektur ist das Nomadentum. Mit der M\u00f6glichkeit, sich von jedem internetf\u00e4higen Endger\u00e4t aus \u00fcber einen einfachen Browser mit der Software zu verbinden. Der zweite nicht zu vernachl\u00e4ssigende Vorteil ist die fl\u00fcssige Navigation f\u00fcr die Nutzer und die schnelle Reaktionszeit der Plattform.  Sie wird im Saas-Modus (Software, die beim Herausgeber gehostet wird) oder On-Premise-Modus (Software, die direkt im Netzwerk des Kunden installiert wird) bereitgestellt.<\/p>\n\n\n\n<p>Um die L\u00f6sung zu implementieren, bietet Ellistat seinen Kunden ein Begleitpaket an. (&gt; Mehr dazu :&nbsp;<a href=\"https:\/\/ellistat.com\/de\/apc-pilotprojekt\/\">Pilotprojekt<\/a>,&nbsp;<a href=\"https:\/\/ellistat.com\/de\/spc-begleitung\/\">SPC-Begleitung<\/a>,&nbsp;<a href=\"https:\/\/ellistat.com\/de\/iqc-begleitung\/\">IQC-Begleitung<\/a>).&nbsp;<\/p>\n\n\n\n<p>Zun\u00e4chst wird eine Diagnose am Standort des Kunden erstellt, um die beste Methode zur Einf\u00fchrung der L\u00f6sung zu ermitteln. Danach folgt die Vorbereitungsphase, die es erm\u00f6glicht, bei der Implementierung pr\u00e4zise zu sein. Schlie\u00dflich wird eine 3- oder 4-t\u00e4gige Schulung vor Ort geplant, je nach Anzahl der Module.<\/p>\n\n\n\n<p>Davy Pillet: \"Wir sind stolz auf die geleistete Arbeit und darauf, den Industrieunternehmen ein komplettes Softwarepaket f\u00fcr die Qualit\u00e4tssicherung in der Produktion anbieten zu k\u00f6nnen. Ellistat stellt die leistungsf\u00e4higste L\u00f6sung auf dem Markt dar, mit einer Full-Web-Technologie, die auf alle Module angewendet wird, f\u00fcr eine extrem einfache, benutzerfreundliche und super ergonomische Nutzung.<\/p>\n\n\n\n<p>* Statistiker, ausgebildet an der Ecole Normale Sup\u00e9rieure de Cachan, Forschungsleiter am SYMME-Labor und Erfinder der Konzepte Tr\u00e4gheitstolerierung und Tr\u00e4gheitssteuerung von Prozessen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ellistat, ein Softwareunternehmen, das f\u00fcr seine APC-Softwarel\u00f6sung zur Automatisierung der Einstellung von Werkzeugmaschinen bekannt ist, bringt ein neues, umfassendes Softwareangebot f\u00fcr die Qualit\u00e4t in der Produktion auf den Markt<\/p>","protected":false},"author":2,"featured_media":170,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,4],"tags":[],"class_list":["post-169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iqc","category-spc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Suite logicielle qualit\u00e9 d\u2019Ellistat<\/title>\n<meta name=\"description\" content=\"Suite logicielle qualit\u00e9 compl\u00e8te. Ellistat se positionne comme un acteur incontournable de la qualit\u00e9 industrielle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ellistat.com\/de\/ellistat-kundigt-umfassende-qualitatssoftware-suite-an\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suite logicielle qualit\u00e9 d\u2019Ellistat\" \/>\n<meta property=\"og:description\" content=\"Suite logicielle qualit\u00e9 compl\u00e8te. Ellistat se positionne comme un acteur incontournable de la qualit\u00e9 industrielle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ellistat.com\/de\/ellistat-kundigt-umfassende-qualitatssoftware-suite-an\/\" \/>\n<meta property=\"og:site_name\" content=\"Ellistat\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-08T07:21:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-23T12:52:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ellistat.com\/wp-content\/uploads\/2024\/08\/Quality-Suit-21-x-14.8-cm-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Davy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/ellistat-annonce-une-suite-logicielle-qualite-complete\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/ellistat-annonce-une-suite-logicielle-qualite-complete\\\/\"},\"author\":{\"name\":\"Davy\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/#\\\/schema\\\/person\\\/e2a04a9eb45bae5d885b534cbf70df8d\"},\"headline\":\"Suite logicielle qualit\u00e9 d\u2019Ellistat\",\"datePublished\":\"2024-08-08T07:21:09+00:00\",\"dateModified\":\"2024-10-23T12:52:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/ellistat-annonce-une-suite-logicielle-qualite-complete\\\/\"},\"wordCount\":1227,\"image\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/ellistat-annonce-une-suite-logicielle-qualite-complete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Quality-Suit-21-x-14.8-cm-1-1.jpg\",\"articleSection\":[\"IQC\",\"SPC\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/ellistat-annonce-une-suite-logicielle-qualite-complete\\\/\",\"url\":\"https:\\\/\\\/ellistat.com\\\/ellistat-annonce-une-suite-logicielle-qualite-complete\\\/\",\"name\":\"Suite logicielle qualit\u00e9 d\u2019Ellistat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/ellistat-annonce-une-suite-logicielle-qualite-complete\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/ellistat-annonce-une-suite-logicielle-qualite-complete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Quality-Suit-21-x-14.8-cm-1-1.jpg\",\"datePublished\":\"2024-08-08T07:21:09+00:00\",\"dateModified\":\"2024-10-23T12:52:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/#\\\/schema\\\/person\\\/e2a04a9eb45bae5d885b534cbf70df8d\"},\"description\":\"Suite logicielle qualit\u00e9 compl\u00e8te. Ellistat se positionne comme un acteur incontournable de la qualit\u00e9 industrielle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/ellistat-annonce-une-suite-logicielle-qualite-complete\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ellistat.com\\\/ellistat-annonce-une-suite-logicielle-qualite-complete\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/ellistat-annonce-une-suite-logicielle-qualite-complete\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Quality-Suit-21-x-14.8-cm-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Quality-Suit-21-x-14.8-cm-1-1.jpg\",\"width\":2000,\"height\":1410,\"caption\":\"Les modules Automated Process Control, SPC, IQC, Metro, non conformit\u00e9, Data Analysis du logiciel qualit\u00e9 Ellistat\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/ellistat-annonce-une-suite-logicielle-qualite-complete\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ellistat.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SPC\",\"item\":\"https:\\\/\\\/ellistat.com\\\/category\\\/spc\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Suite logicielle qualit\u00e9 d\u2019Ellistat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/#website\",\"url\":\"https:\\\/\\\/ellistat.com\\\/\",\"name\":\"Ellistat\",\"description\":\"La suite qualit\u00e9 de l&#039;industrie m\u00e9canique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ellistat.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/#\\\/schema\\\/person\\\/e2a04a9eb45bae5d885b534cbf70df8d\",\"name\":\"Davy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/litespeed\\\/avatar\\\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658\",\"url\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/litespeed\\\/avatar\\\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658\",\"contentUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/litespeed\\\/avatar\\\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658\",\"caption\":\"Davy\"},\"sameAs\":[\"https:\\\/\\\/ellistat.com\"],\"url\":\"https:\\\/\\\/ellistat.com\\\/de\\\/author\\\/elliadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ellistats Qualit\u00e4tssoftware-Suite","description":"Umfassende Software-Suite f\u00fcr Qualit\u00e4t. Ellistat positioniert sich als unumg\u00e4nglicher Akteur im Bereich der industriellen Qualit\u00e4t.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ellistat.com\/de\/ellistat-kundigt-umfassende-qualitatssoftware-suite-an\/","og_locale":"de_DE","og_type":"article","og_title":"Suite logicielle qualit\u00e9 d\u2019Ellistat","og_description":"Suite logicielle qualit\u00e9 compl\u00e8te. Ellistat se positionne comme un acteur incontournable de la qualit\u00e9 industrielle.","og_url":"https:\/\/ellistat.com\/de\/ellistat-kundigt-umfassende-qualitatssoftware-suite-an\/","og_site_name":"Ellistat","article_published_time":"2024-08-08T07:21:09+00:00","article_modified_time":"2024-10-23T12:52:17+00:00","og_image":[{"width":2000,"height":1410,"url":"https:\/\/ellistat.com\/wp-content\/uploads\/2024\/08\/Quality-Suit-21-x-14.8-cm-1-1.jpg","type":"image\/jpeg"}],"author":"Davy","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Davy","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ellistat.com\/ellistat-annonce-une-suite-logicielle-qualite-complete\/#article","isPartOf":{"@id":"https:\/\/ellistat.com\/ellistat-annonce-une-suite-logicielle-qualite-complete\/"},"author":{"name":"Davy","@id":"https:\/\/ellistat.com\/#\/schema\/person\/e2a04a9eb45bae5d885b534cbf70df8d"},"headline":"Suite logicielle qualit\u00e9 d\u2019Ellistat","datePublished":"2024-08-08T07:21:09+00:00","dateModified":"2024-10-23T12:52:17+00:00","mainEntityOfPage":{"@id":"https:\/\/ellistat.com\/ellistat-annonce-une-suite-logicielle-qualite-complete\/"},"wordCount":1227,"image":{"@id":"https:\/\/ellistat.com\/ellistat-annonce-une-suite-logicielle-qualite-complete\/#primaryimage"},"thumbnailUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/2024\/08\/Quality-Suit-21-x-14.8-cm-1-1.jpg","articleSection":["IQC","SPC"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/ellistat.com\/ellistat-annonce-une-suite-logicielle-qualite-complete\/","url":"https:\/\/ellistat.com\/ellistat-annonce-une-suite-logicielle-qualite-complete\/","name":"Ellistats Qualit\u00e4tssoftware-Suite","isPartOf":{"@id":"https:\/\/ellistat.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ellistat.com\/ellistat-annonce-une-suite-logicielle-qualite-complete\/#primaryimage"},"image":{"@id":"https:\/\/ellistat.com\/ellistat-annonce-une-suite-logicielle-qualite-complete\/#primaryimage"},"thumbnailUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/2024\/08\/Quality-Suit-21-x-14.8-cm-1-1.jpg","datePublished":"2024-08-08T07:21:09+00:00","dateModified":"2024-10-23T12:52:17+00:00","author":{"@id":"https:\/\/ellistat.com\/#\/schema\/person\/e2a04a9eb45bae5d885b534cbf70df8d"},"description":"Umfassende Software-Suite f\u00fcr Qualit\u00e4t. Ellistat positioniert sich als unumg\u00e4nglicher Akteur im Bereich der industriellen Qualit\u00e4t.","breadcrumb":{"@id":"https:\/\/ellistat.com\/ellistat-annonce-une-suite-logicielle-qualite-complete\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ellistat.com\/ellistat-annonce-une-suite-logicielle-qualite-complete\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ellistat.com\/ellistat-annonce-une-suite-logicielle-qualite-complete\/#primaryimage","url":"https:\/\/ellistat.com\/wp-content\/uploads\/2024\/08\/Quality-Suit-21-x-14.8-cm-1-1.jpg","contentUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/2024\/08\/Quality-Suit-21-x-14.8-cm-1-1.jpg","width":2000,"height":1410,"caption":"Les modules Automated Process Control, SPC, IQC, Metro, non conformit\u00e9, Data Analysis du logiciel qualit\u00e9 Ellistat"},{"@type":"BreadcrumbList","@id":"https:\/\/ellistat.com\/ellistat-annonce-une-suite-logicielle-qualite-complete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ellistat.com\/"},{"@type":"ListItem","position":2,"name":"SPC","item":"https:\/\/ellistat.com\/category\/spc\/"},{"@type":"ListItem","position":3,"name":"Suite logicielle qualit\u00e9 d\u2019Ellistat"}]},{"@type":"WebSite","@id":"https:\/\/ellistat.com\/#website","url":"https:\/\/ellistat.com\/","name":"Ellistat","description":"Die Qualit\u00e4tssuite der Maschinenbauindustrie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ellistat.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/ellistat.com\/#\/schema\/person\/e2a04a9eb45bae5d885b534cbf70df8d","name":"Davy","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ellistat.com\/wp-content\/litespeed\/avatar\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658","url":"https:\/\/ellistat.com\/wp-content\/litespeed\/avatar\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658","contentUrl":"https:\/\/ellistat.com\/wp-content\/litespeed\/avatar\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658","caption":"Davy"},"sameAs":["https:\/\/ellistat.com"],"url":"https:\/\/ellistat.com\/de\/author\/elliadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/posts\/169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/comments?post=169"}],"version-history":[{"count":3,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/posts\/169\/revisions"}],"predecessor-version":[{"id":402,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/posts\/169\/revisions\/402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/media\/170"}],"wp:attachment":[{"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/media?parent=169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/categories?post=169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/tags?post=169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}