{"id":2708,"date":"2024-10-15T17:05:11","date_gmt":"2024-10-15T15:05:11","guid":{"rendered":"https:\/\/ellistat.com\/?p=2708"},"modified":"2024-11-26T10:27:59","modified_gmt":"2024-11-26T09:27:59","slug":"spc-oder-stichprobenkontrolle","status":"publish","type":"post","link":"https:\/\/ellistat.com\/de\/spc-ou-controle-par-echantillonnage\/","title":{"rendered":"SPC oder Stichprobenkontrolle"},"content":{"rendered":"<p>Wenn man eine Produktionskontrolle durchf\u00fchrt, stellt sich oft die Frage nach der Art der Kontrolle. Welches Modul soll ich verwenden, das SPC- oder das IQC-Modul (Stichprobenkontrolle).<\/p>\n\n\n\n<p>Um diese Frage richtig beantworten zu k\u00f6nnen, m\u00fcssen Sie den Unterschied zwischen diesen beiden Arten von Kontrollen deutlich machen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SPC<\/h2>\n\n\n\n<p>Ziel der SPC ist es, einen Prozess w\u00e4hrend der Produktion zu verfolgen. Der Begriff der Zeitlichkeit ist wichtig, da die Teile in einer bestimmten Reihenfolge produziert werden und die Regelkarte die Berichterstattung \u00fcber den Produktionsablauf erm\u00f6glicht. Au\u00dferdem erm\u00f6glicht die SPC die Verfolgung eines Prozesses in Echtzeit, d. h. eine Abweichung im Prozess erm\u00f6glicht es, eine Warnung an den Bediener zu senden, damit dieser reagieren kann.<\/p>\n\n\n\n<p>Der Begriff der Gesamtstichprobe ist in der SPC nicht besonders wichtig, wir konzentrieren uns nur auf:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Kurzfristige Probenahme: Bei jeder Probenahme werden 1, 3 oder 5 Teile gemessen, um sowohl die Zentrierung als auch die Streuung des Prozesses zum Zeitpunkt der Probenahme zu charakterisieren.<\/li>\n\n\n\n<li>Zeit zwischen zwei Probenahmen: Zwischen zwei Probenahmen kann die Maschine gedriftet sein, daher ist es wichtig, eine Probenahmefrequenz beizubehalten, die es erm\u00f6glicht, eine Drift fr\u00fchzeitig zu erkennen. In der SPC h\u00e4ngt die H\u00e4ufigkeit der Probenahme NICHT von der Chargengr\u00f6\u00dfe ab, sondern nur von der Drift des Prozesses.<\/li>\n<\/ul>\n\n\n\n<p>Mit der SPC ist es durchaus m\u00f6glich, aus dem Messergebnis einen Fehlerprozentsatz zu berechnen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">IQC (Stichprobenkontrolle)<\/h2>\n\n\n\n<p>Die Stichprobenkontrolle soll qualifizieren, ob die produzierte Charge die festgelegten Qualit\u00e4tsanforderungen erf\u00fcllt. Sie wird daher POSTERIORI durchgef\u00fchrt. Bei der CQI ist der Begriff der Zeitlichkeit nicht von Bedeutung. Die Teile sind alle produziert worden, daher werden wir eine Stichprobe entnehmen, ohne die Reihenfolge der Produktion zu ber\u00fccksichtigen.<\/p>\n\n\n\n<p>Der Begriff der Gesamtstichprobe ist f\u00fcr die Qualit\u00e4tssicherung von grundlegender Bedeutung, da bei der Stichprobenkontrolle eine bestimmte Anzahl von Proben gemessen wird, um das Los zu best\u00e4tigen oder zur\u00fcckzuweisen. Die Anzahl der Stichproben h\u00e4ngt von folgenden Faktoren ab<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Von der Gr\u00f6\u00dfe des Loses<\/li>\n\n\n\n<li>Von der Art der Kontrolle, d. h. dem AQL (Acceptable Quality Level) und der Strenge der Kontrolle<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Wie man das Beste aus beiden Welten bekommt<\/h2>\n\n\n\n<p>Manchmal m\u00f6chte man eine Charge, die gerade produziert wird, annehmen oder ablehnen k\u00f6nnen. Man muss also eine Gesamtprobe (um die Charge validieren zu k\u00f6nnen) einer Charge garantieren, die selbst gerade produziert wird.<\/p>\n\n\n\n<p>Um dies tun zu k\u00f6nnen, m\u00fcssen die Regeln der klassischen SPC angewendet werden, solange sich die Charge in der Produktion befindet. Die Probenahme zu diesem Zeitpunkt h\u00e4ngt nicht von der Losgr\u00f6\u00dfe ab, sondern dient dazu, m\u00f6gliche Prozessabweichungen zu erkennen.<\/p>\n\n\n\n<p>Sobald die Charge produziert ist, schaltet man alle Messungen in das IQC-Modul um. Wenn die Anzahl der Messungen ausreichend ist, k\u00f6nnen wir die Produktion direkt freigeben oder nicht freigeben. Andernfalls gen\u00fcgt es, die Anzahl der fehlenden Produkte zu messen, um uns zu erm\u00f6glichen, Stichprobenkontrollen direkt in der Produktion durchzuf\u00fchren.<\/p>","protected":false},"excerpt":{"rendered":"<p>Lorsque l&rsquo;on r\u00e9alise un contr\u00f4le en production se pose souvent la question du type de contr\u00f4le. Quel module dois-je utiliser, le module SPC ou IQC (Contr\u00f4le par \u00e9chantillonnage). Pour y r\u00e9pondre correctement, il faut bien distinguer la diff\u00e9rence entre ces deux types de contr\u00f4les. SPC Le SPC a pour objectif de suivre un proc\u00e9d\u00e9 en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2934,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,4],"tags":[],"class_list":["post-2708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iqc","category-spc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SPC ou contr\u00f4le par \u00e9chantillonnage - Ellistat<\/title>\n<meta name=\"description\" content=\"Lorsque l&#039;on r\u00e9alise un contr\u00f4le en production se pose souvent la question du type de contr\u00f4le. Quel module dois-je utiliser SPC ou IQC ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ellistat.com\/de\/spc-oder-stichprobenkontrolle\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SPC ou contr\u00f4le par \u00e9chantillonnage - Ellistat\" \/>\n<meta property=\"og:description\" content=\"Lorsque l&#039;on r\u00e9alise un contr\u00f4le en production se pose souvent la question du type de contr\u00f4le. Quel module dois-je utiliser SPC ou IQC ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ellistat.com\/de\/spc-oder-stichprobenkontrolle\/\" \/>\n<meta property=\"og:site_name\" content=\"Ellistat\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-15T15:05:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-26T09:27:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ellistat.com\/wp-content\/uploads\/SPC-vs-IQC-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"851\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Davy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/\"},\"author\":{\"name\":\"Davy\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/#\\\/schema\\\/person\\\/e2a04a9eb45bae5d885b534cbf70df8d\"},\"headline\":\"SPC ou contr\u00f4le par \u00e9chantillonnage\",\"datePublished\":\"2024-10-15T15:05:11+00:00\",\"dateModified\":\"2024-11-26T09:27:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/\"},\"wordCount\":557,\"image\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/SPC-vs-IQC-2.png\",\"articleSection\":[\"IQC\",\"SPC\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/\",\"url\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/\",\"name\":\"SPC ou contr\u00f4le par \u00e9chantillonnage - Ellistat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/SPC-vs-IQC-2.png\",\"datePublished\":\"2024-10-15T15:05:11+00:00\",\"dateModified\":\"2024-11-26T09:27:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/#\\\/schema\\\/person\\\/e2a04a9eb45bae5d885b534cbf70df8d\"},\"description\":\"Lorsque l'on r\u00e9alise un contr\u00f4le en production se pose souvent la question du type de contr\u00f4le. Quel module dois-je utiliser SPC ou IQC ?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/SPC-vs-IQC-2.png\",\"contentUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/SPC-vs-IQC-2.png\",\"width\":851,\"height\":315,\"caption\":\"SPC ou contr\u00f4le par \u00e9chantillonnage ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ellistat.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IQC\",\"item\":\"https:\\\/\\\/ellistat.com\\\/category\\\/iqc\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SPC ou contr\u00f4le par \u00e9chantillonnage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/#website\",\"url\":\"https:\\\/\\\/ellistat.com\\\/\",\"name\":\"Ellistat\",\"description\":\"La suite qualit\u00e9 de l&#039;industrie m\u00e9canique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ellistat.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/#\\\/schema\\\/person\\\/e2a04a9eb45bae5d885b534cbf70df8d\",\"name\":\"Davy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/litespeed\\\/avatar\\\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658\",\"url\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/litespeed\\\/avatar\\\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658\",\"contentUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/litespeed\\\/avatar\\\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658\",\"caption\":\"Davy\"},\"sameAs\":[\"https:\\\/\\\/ellistat.com\"],\"url\":\"https:\\\/\\\/ellistat.com\\\/de\\\/author\\\/elliadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SPC oder Stichprobenkontrolle - Ellistat","description":"Wenn man eine Kontrolle in der Produktion durchf\u00fchrt, stellt sich oft die Frage nach der Art der Kontrolle. Welches Modul soll ich verwenden SPC oder IQC?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ellistat.com\/de\/spc-oder-stichprobenkontrolle\/","og_locale":"de_DE","og_type":"article","og_title":"SPC ou contr\u00f4le par \u00e9chantillonnage - Ellistat","og_description":"Lorsque l'on r\u00e9alise un contr\u00f4le en production se pose souvent la question du type de contr\u00f4le. Quel module dois-je utiliser SPC ou IQC ?","og_url":"https:\/\/ellistat.com\/de\/spc-oder-stichprobenkontrolle\/","og_site_name":"Ellistat","article_published_time":"2024-10-15T15:05:11+00:00","article_modified_time":"2024-11-26T09:27:59+00:00","og_image":[{"width":851,"height":315,"url":"https:\/\/ellistat.com\/wp-content\/uploads\/SPC-vs-IQC-2.png","type":"image\/png"}],"author":"Davy","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Davy","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/#article","isPartOf":{"@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/"},"author":{"name":"Davy","@id":"https:\/\/ellistat.com\/#\/schema\/person\/e2a04a9eb45bae5d885b534cbf70df8d"},"headline":"SPC ou contr\u00f4le par \u00e9chantillonnage","datePublished":"2024-10-15T15:05:11+00:00","dateModified":"2024-11-26T09:27:59+00:00","mainEntityOfPage":{"@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/"},"wordCount":557,"image":{"@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/#primaryimage"},"thumbnailUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/SPC-vs-IQC-2.png","articleSection":["IQC","SPC"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/","url":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/","name":"SPC oder Stichprobenkontrolle - Ellistat","isPartOf":{"@id":"https:\/\/ellistat.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/#primaryimage"},"image":{"@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/#primaryimage"},"thumbnailUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/SPC-vs-IQC-2.png","datePublished":"2024-10-15T15:05:11+00:00","dateModified":"2024-11-26T09:27:59+00:00","author":{"@id":"https:\/\/ellistat.com\/#\/schema\/person\/e2a04a9eb45bae5d885b534cbf70df8d"},"description":"Wenn man eine Kontrolle in der Produktion durchf\u00fchrt, stellt sich oft die Frage nach der Art der Kontrolle. Welches Modul soll ich verwenden SPC oder IQC?","breadcrumb":{"@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/#primaryimage","url":"https:\/\/ellistat.com\/wp-content\/uploads\/SPC-vs-IQC-2.png","contentUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/SPC-vs-IQC-2.png","width":851,"height":315,"caption":"SPC ou contr\u00f4le par \u00e9chantillonnage ?"},{"@type":"BreadcrumbList","@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ellistat.com\/"},{"@type":"ListItem","position":2,"name":"IQC","item":"https:\/\/ellistat.com\/category\/iqc\/"},{"@type":"ListItem","position":3,"name":"SPC ou contr\u00f4le par \u00e9chantillonnage"}]},{"@type":"WebSite","@id":"https:\/\/ellistat.com\/#website","url":"https:\/\/ellistat.com\/","name":"Ellistat","description":"Die Qualit\u00e4tssuite der Maschinenbauindustrie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ellistat.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/ellistat.com\/#\/schema\/person\/e2a04a9eb45bae5d885b534cbf70df8d","name":"Davy","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ellistat.com\/wp-content\/litespeed\/avatar\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658","url":"https:\/\/ellistat.com\/wp-content\/litespeed\/avatar\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658","contentUrl":"https:\/\/ellistat.com\/wp-content\/litespeed\/avatar\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658","caption":"Davy"},"sameAs":["https:\/\/ellistat.com"],"url":"https:\/\/ellistat.com\/de\/author\/elliadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/posts\/2708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/comments?post=2708"}],"version-history":[{"count":2,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/posts\/2708\/revisions"}],"predecessor-version":[{"id":2717,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/posts\/2708\/revisions\/2717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/media\/2934"}],"wp:attachment":[{"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/media?parent=2708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/categories?post=2708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellistat.com\/de\/wp-json\/wp\/v2\/tags?post=2708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}