{"id":2664,"date":"2024-10-09T11:02:27","date_gmt":"2024-10-09T09:02:27","guid":{"rendered":"https:\/\/ellistat.com\/?post_type=ressource-pedagogiqu&#038;p=2664"},"modified":"2024-10-24T15:52:31","modified_gmt":"2024-10-24T13:52:31","slug":"galga-rr-atributo","status":"publish","type":"ressource-pedagogiqu","link":"https:\/\/ellistat.com\/es\/ressource-pedagogiqu\/gage-rr-attribut\/","title":{"rendered":"Medidor R&amp;R Atributo"},"content":{"rendered":"<p>La R&amp;R de atributos se refiere espec\u00edficamente a caracter\u00edsticas de atributos, es decir, caracter\u00edsticas que se categorizan en lugar de medirse num\u00e9ricamente. Por ejemplo, caracter\u00edsticas como el cumplimiento de una especificaci\u00f3n, la presencia o ausencia de un defecto, etc., se categorizan en lugar de medirse num\u00e9ricamente.&nbsp;<\/p>\n\n\n\n<p>La <a href=\"https:\/\/competences.afnor.org\/actualites\/le-msa-measurement-system-analysis-de-quoi-sagit-il\">Norma MSA<\/a> (An\u00e1lisis de Sistemas de Medici\u00f3n), proporciona directrices y metodolog\u00edas para evaluar y mejorar la fiabilidad de un sistema de medici\u00f3n, ya sea para mediciones continuas o de atributos. Para las caracter\u00edsticas de atributos, el MSA propone m\u00e9todos espec\u00edficos para evaluar la repetibilidad y la reproducibilidad, en particular utilizando el m\u00e9todo de atributos Gage R&amp;R con el indicador Kappa de Cohen (v\u00e9anse los detalles).\u00a0<\/p>\n\n\n\n<p>Seg\u00fan la norma MSA, para llevar a cabo un estudio de atributos Gage R&amp;R, se recomiendan generalmente los siguientes pasos:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Selecci\u00f3n de las caracter\u00edsticas de los atributos<\/strong> Identifique las caracter\u00edsticas de los atributos que desea evaluar. Ejemplo: Aspecto\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Definici\u00f3n de categor\u00edas<\/strong> Definir claramente las categor\u00edas o clasificaciones para cada caracter\u00edstica de atributo. (CF\/NCF) \/ (OK\/KO) etc...\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Selecci\u00f3n de operadores<\/strong> Elija a los operarios que realizar\u00e1n las mediciones. Es importante que estos operarios sean representativos de los que utilizar\u00e1n el sistema de medici\u00f3n en la pr\u00e1ctica.\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Recogida de datos<\/strong> Medir las caracter\u00edsticas de los atributos de una muestra de piezas utilizando el sistema de medici\u00f3n en cuesti\u00f3n. Este paso requiere que un experto caracterice las muestras antes del estudio Gage R&amp;R. A continuaci\u00f3n, cada operario debe medir cada pieza.\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>An\u00e1lisis de datos<\/strong> Utilizar m\u00e9todos estad\u00edsticos adecuados para desglosar la variaci\u00f3n total en componentes atribuibles a la repetibilidad (variaci\u00f3n debida al mismo operario) y a la reproducibilidad (variaci\u00f3n debida a diferentes operarios).\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Interpretaci\u00f3n de los resultados<\/strong> Evaluar la proporci\u00f3n de la variaci\u00f3n total atribuible a la repetibilidad y la reproducibilidad. Si estos componentes de la variaci\u00f3n son peque\u00f1os en relaci\u00f3n con el intervalo de tolerancia de la caracter\u00edstica, el sistema de medici\u00f3n se considera fiable para las caracter\u00edsticas del atributo.\u00a0<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Kappa de Cohen<\/strong>&nbsp;<\/h2>\n\n\n\n<p>Le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Kappa_de_Cohen\">Coeficiente kappa de Cohen<\/a>El coeficiente kappa, a menudo denominado simplemente \"kappa\", es una medida estad\u00edstica utilizada para evaluar la concordancia entre dos observadores o m\u00e9todos de medici\u00f3n a la hora de clasificar elementos en categor\u00edas discretas. Se utiliza mucho en investigaci\u00f3n m\u00e9dica, epidemiolog\u00eda, psicolog\u00eda y otras disciplinas en las que la concordancia entre observadores o m\u00e9todos es importante.\u00a0<\/p>\n\n\n\n<p>El coeficiente kappa tiene en cuenta tanto el acuerdo real entre observadores como el acuerdo que podr\u00eda deberse al azar. Por tanto, corrige el \u00edndice simple de acuerdo bruto teniendo en cuenta la probabilidad de acuerdo debido al azar.&nbsp;<\/p>\n\n\n\n<p>El coeficiente kappa se calcula mediante la f\u00f3rmula :&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><span class=\"wp-katex-eq\" data-display=\"false\">Kappa =\\frac{P_{0}-P_{e}}{1-P_{e}}<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\ud835\udc430 es la proporci\u00f3n de acuerdo observada entre los observadores.\u00a0<\/li>\n\n\n\n<li>\ud835\udc43\ud835\udc52 es la proporci\u00f3n de concordancia esperada debida al azar.\u00a0<\/li>\n<\/ul>\n\n\n\n<p>El coeficiente kappa puede variar de -1 a 1, donde :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Kappa = 1, indica un acuerdo perfecto entre observadores.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Kappa=0, indica una concordancia equivalente a la que podr\u00eda obtenerse por azar.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Kappa=-1, indica un desacuerdo total entre los observadores.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><strong>Eficacia :<\/strong>&nbsp;<\/p>\n\n\n\n<p>La eficacia de un m\u00e9todo de medici\u00f3n de atributos cuantifica la tasa de buenas decisiones sobre el n\u00famero total de oportunidades.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><span class=\"wp-katex-eq\" data-display=\"false\">Eficacia = \\frac{texto{n\u00famero de decisiones correctas}}{texto{n\u00famero de piezas inspeccionadas}}<\/span><\/p>\n\n\n\n<p><strong>Tasa de error :<\/strong>&nbsp;<\/p>\n\n\n\n<p>La tasa de error expresa la frecuencia con la que una pieza no conforme es considerada err\u00f3neamente por el operario como conforme.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><span class=\"wp-katex-eq\" data-display=\"false\">Tasa de error = {{n\u00famero de decisiones \"conformes\" sabiendo que la pieza es \"no conforme\"}} {{n\u00famero de oportunidades para una pieza no conforme}}.<\/span><\/p>\n\n\n\n<p><strong>Tasa de falsas alarmas :<\/strong>&nbsp;<\/p>\n\n\n\n<p>El porcentaje de error expresa la frecuencia con la que una pieza conforme es considerada err\u00f3neamente por el operador como no conforme.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><span class=\"wp-katex-eq\" data-display=\"false\">Falsas alarmas = {{n\u00famero de decisiones \"no conformes\" sabiendo que la pieza es \"conforme\"}} {{n\u00famero de oportunidades para una pieza conforme}}.<\/span><\/p>\n\n\n\n<p><\/p>","protected":false},"featured_media":909,"template":"","meta":{"_acf_changed":false},"menu-ressource-pedagogique":[26],"class_list":["post-2664","ressource-pedagogiqu","type-ressource-pedagogiqu","status-publish","has-post-thumbnail","hentry","menu-ressource-pedagogique-2-gage-rr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gage R&amp;R Attribut - Ellistat<\/title>\n<meta name=\"description\" content=\"La gage R&amp;R attribut concerne sp\u00e9cifiquement les caract\u00e9ristiques attributaires, qui sont cat\u00e9goris\u00e9es plut\u00f4t que mesur\u00e9es num\u00e9riquement.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ellistat.com\/es\/recurso-educativo\/galga-rr-atributo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gage R&amp;R Attribut - Ellistat\" \/>\n<meta property=\"og:description\" content=\"La gage R&amp;R attribut concerne sp\u00e9cifiquement les caract\u00e9ristiques attributaires, qui sont cat\u00e9goris\u00e9es plut\u00f4t que mesur\u00e9es num\u00e9riquement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ellistat.com\/es\/recurso-educativo\/galga-rr-atributo\/\" \/>\n<meta property=\"og:site_name\" content=\"Ellistat\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-24T13:52:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ellistat.com\/wp-content\/uploads\/2024\/09\/GageRR.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"873\" \/>\n\t<meta property=\"og:image:height\" content=\"679\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/ressource-pedagogiqu\\\/gage-rr-attribut\\\/\",\"url\":\"https:\\\/\\\/ellistat.com\\\/ressource-pedagogiqu\\\/gage-rr-attribut\\\/\",\"name\":\"Gage R&amp;R Attribut - Ellistat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/ressource-pedagogiqu\\\/gage-rr-attribut\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/ressource-pedagogiqu\\\/gage-rr-attribut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/GageRR.webp\",\"datePublished\":\"2024-10-09T09:02:27+00:00\",\"dateModified\":\"2024-10-24T13:52:31+00:00\",\"description\":\"La gage R&R attribut concerne sp\u00e9cifiquement les caract\u00e9ristiques attributaires, qui sont cat\u00e9goris\u00e9es plut\u00f4t que mesur\u00e9es num\u00e9riquement.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/ressource-pedagogiqu\\\/gage-rr-attribut\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ellistat.com\\\/ressource-pedagogiqu\\\/gage-rr-attribut\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/ressource-pedagogiqu\\\/gage-rr-attribut\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/GageRR.webp\",\"contentUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/GageRR.webp\",\"width\":873,\"height\":679,\"caption\":\"MSA et Gage R&R avec Ellistat Data Analysis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/ressource-pedagogiqu\\\/gage-rr-attribut\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ellistat.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gage R&amp;R Attribut\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/#website\",\"url\":\"https:\\\/\\\/ellistat.com\\\/\",\"name\":\"Ellistat\",\"description\":\"La suite qualit\u00e9 de l&#039;industrie m\u00e9canique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ellistat.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gage R&amp;R Attribut - Ellistat","description":"El R&amp;R de atributos se refiere espec\u00edficamente a las caracter\u00edsticas de los atributos, que se categorizan en lugar de medirse num\u00e9ricamente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ellistat.com\/es\/recurso-educativo\/galga-rr-atributo\/","og_locale":"es_ES","og_type":"article","og_title":"Gage R&amp;R Attribut - Ellistat","og_description":"La gage R&R attribut concerne sp\u00e9cifiquement les caract\u00e9ristiques attributaires, qui sont cat\u00e9goris\u00e9es plut\u00f4t que mesur\u00e9es num\u00e9riquement.","og_url":"https:\/\/ellistat.com\/es\/recurso-educativo\/galga-rr-atributo\/","og_site_name":"Ellistat","article_modified_time":"2024-10-24T13:52:31+00:00","og_image":[{"width":873,"height":679,"url":"https:\/\/ellistat.com\/wp-content\/uploads\/2024\/09\/GageRR.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ellistat.com\/ressource-pedagogiqu\/gage-rr-attribut\/","url":"https:\/\/ellistat.com\/ressource-pedagogiqu\/gage-rr-attribut\/","name":"Gage R&amp;R Attribut - Ellistat","isPartOf":{"@id":"https:\/\/ellistat.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ellistat.com\/ressource-pedagogiqu\/gage-rr-attribut\/#primaryimage"},"image":{"@id":"https:\/\/ellistat.com\/ressource-pedagogiqu\/gage-rr-attribut\/#primaryimage"},"thumbnailUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/2024\/09\/GageRR.webp","datePublished":"2024-10-09T09:02:27+00:00","dateModified":"2024-10-24T13:52:31+00:00","description":"El R&amp;R de atributos se refiere espec\u00edficamente a las caracter\u00edsticas de los atributos, que se categorizan en lugar de medirse num\u00e9ricamente.","breadcrumb":{"@id":"https:\/\/ellistat.com\/ressource-pedagogiqu\/gage-rr-attribut\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ellistat.com\/ressource-pedagogiqu\/gage-rr-attribut\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ellistat.com\/ressource-pedagogiqu\/gage-rr-attribut\/#primaryimage","url":"https:\/\/ellistat.com\/wp-content\/uploads\/2024\/09\/GageRR.webp","contentUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/2024\/09\/GageRR.webp","width":873,"height":679,"caption":"MSA et Gage R&R avec Ellistat Data Analysis"},{"@type":"BreadcrumbList","@id":"https:\/\/ellistat.com\/ressource-pedagogiqu\/gage-rr-attribut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ellistat.com\/"},{"@type":"ListItem","position":2,"name":"Gage R&amp;R Attribut"}]},{"@type":"WebSite","@id":"https:\/\/ellistat.com\/#website","url":"https:\/\/ellistat.com\/","name":"Ellistat","description":"La suite de calidad para la industria de la ingenier\u00eda mec\u00e1nica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ellistat.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/ellistat.com\/es\/wp-json\/wp\/v2\/ressource-pedagogiqu\/2664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellistat.com\/es\/wp-json\/wp\/v2\/ressource-pedagogiqu"}],"about":[{"href":"https:\/\/ellistat.com\/es\/wp-json\/wp\/v2\/types\/ressource-pedagogiqu"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellistat.com\/es\/wp-json\/wp\/v2\/media\/909"}],"wp:attachment":[{"href":"https:\/\/ellistat.com\/es\/wp-json\/wp\/v2\/media?parent=2664"}],"wp:term":[{"taxonomy":"menu-ressource-pedagogique","embeddable":true,"href":"https:\/\/ellistat.com\/es\/wp-json\/wp\/v2\/menu-ressource-pedagogique?post=2664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}