{"id":4649,"date":"2026-08-12T16:58:48","date_gmt":"2026-08-12T14:58:48","guid":{"rendered":"https:\/\/ellistat.com\/?post_type=guide-dutilisateur&#038;p=4649"},"modified":"2026-08-12T16:58:48","modified_gmt":"2026-08-12T14:58:48","slug":"come-scegliere","status":"publish","type":"guide-dutilisateur","link":"https:\/\/ellistat.com\/it\/guide-dutilisateur\/comment-choisir\/","title":{"rendered":"Come scegliere?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Questa \u00e8 la pagina iniziale del menu, ed \u00e8 il punto di partenza ideale quando non si sa da dove cominciare.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"644\" height=\"424\" src=\"https:\/\/ellistat.com\/wp-content\/uploads\/doe1.png\" alt=\"\" class=\"wp-image-4650\" srcset=\"https:\/\/ellistat.com\/wp-content\/uploads\/doe1.png 644w, https:\/\/ellistat.com\/wp-content\/uploads\/doe1-300x198.png 300w, https:\/\/ellistat.com\/wp-content\/uploads\/doe1-18x12.png 18w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">1. Descrivere la propria esigenza<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il riquadro a sinistra, \u00abLe vostre esigenze\u00bb, comprende cinque criteri. Solo il primo \u00e8 obbligatorio.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><td><strong>Criteri<\/strong><\/td><td><strong>Valori<\/strong><\/td><\/tr><\/thead><tbody><tr><td><strong>Obiettivo<\/strong><\/td><td>Setacciare \/ Sgrossare \u00b7 Modellare con interazioni \u00b7 Modellare in modo dettagliato (non lineare) \u00b7 Ottimizzare una risposta \u00b7 Completare un piano esistente<\/td><\/tr><tr><td><strong>Numero di fattori<\/strong><\/td><td>2 \u2013 3 \u00b7 4 \u2013 6 \u00b7 7 e oltre<\/td><\/tr><tr><td><strong>Livelli per fattore<\/strong><\/td><td>2 livelli \u00b7 3 livelli \u00b7 Variabile<\/td><\/tr><tr><td><strong>Tipi di fattori<\/strong><\/td><td>Quantitativi \u00b7 Qualitativi \u00b7 Misti<\/td><\/tr><tr><td><strong>Bilancio per le prove<\/strong><\/td><td>un numero massimo di tentativi<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Alcune combinazioni sono incompatibili e il pulsante corrispondente viene disattivato: l\u2019opzione \u00abModellazione dettagliata (non lineare)\u00bb esclude l\u2019opzione \u00ab2 livelli\u00bb, poich\u00e9 non \u00e8 possibile stimare una curvatura su due punti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una barra riassuntiva riporta la ricerca \u00abStai cercando: \u2026\u00bb e indica il numero di risultati consigliati. Il pulsante \u00abReimposta\u00bb cancella i filtri.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Leggi le schede<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A ogni piano viene assegnata una scheda colorata in base al suo stato:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><td><strong>Stato<\/strong><\/td><td><strong>Colore<\/strong><\/td><td><strong>Significato<\/strong><\/td><\/tr><\/thead><tbody><tr><td><strong>Consigliato<\/strong><\/td><td>verde<\/td><td>Compatibile con tutti i criteri specificati.<\/td><\/tr><tr><td><strong>Compatibile<\/strong><\/td><td>arancione<\/td><td>Utilizzabile, ma parzialmente adeguato rispetto ad almeno un criterio.<\/td><\/tr><tr><td><strong>Escluso<\/strong><\/td><td>grigio<\/td><td>Incompatibile. La scheda mostra il&nbsp;<strong>motivo di esclusione<\/strong>.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La scheda fornisce la descrizione del piano, le sue\u00a0<strong>benefici<\/strong>\u00a0e i suoi\u00a0<strong>svantaggi<\/strong>\u00a0in due colonne, le etichette delle caratteristiche (livelli, intervallo di prova, tipi di fattori accettati): quelle che soddisfano un criterio da voi specificato si evidenziano in blu e compare un pulsante \u00abVai alla pagina\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udca1 Le schede scartate rimangono visualizzate, di proposito. Il motivo dell\u2019esclusione \u00e8 spesso pi\u00f9 istruttivo della raccomandazione: \u00abRichiede solo fattori a 2 livelli\u00bb, \u00abLimitato a un massimo di 6 fattori\u00bb, \u00abNon consente di ampliare un piano esistente\u00bb. Si apprende l\u2019ambito di applicazione di ciascuna famiglia leggendo il motivo per cui non \u00e8 adatta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a0\ufe0f La pagina riflette su ci\u00f2 che voi&nbsp;<strong>dichiarate<\/strong>, non sul contenuto del vostro progetto. Non tiene conto della tabella dei fattori: si tratta di una guida decisionale, non di una diagnosi.<\/p>","protected":false},"featured_media":0,"menu_order":30,"template":"","meta":{"_acf_changed":true},"menu-guide-dutilisateur":[24],"class_list":["post-4649","guide-dutilisateur","type-guide-dutilisateur","status-publish","hentry","menu-guide-dutilisateur-7-doe-plans-dexperiences"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment choisir ? - Ellistat<\/title>\n<meta name=\"description\" content=\"D\u00e9crivez votre objectif, votre nombre de facteurs et votre budget d&#039;essais : l&#039;assistant Ellistat recommande le plan d&#039;exp\u00e9riences adapt\u00e9 et explique pourquoi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ellistat.com\/it\/guida-per-lutente\/come-scegliere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment choisir ? - Ellistat\" \/>\n<meta property=\"og:description\" content=\"D\u00e9crivez votre objectif, votre nombre de facteurs et votre budget d&#039;essais : l&#039;assistant Ellistat recommande le plan d&#039;exp\u00e9riences adapt\u00e9 et explique pourquoi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ellistat.com\/it\/guida-per-lutente\/come-scegliere\/\" \/>\n<meta property=\"og:site_name\" content=\"Ellistat\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ellistat.com\/wp-content\/uploads\/doe1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"644\" \/>\n\t<meta property=\"og:image:height\" content=\"424\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/comment-choisir\\\/\",\"url\":\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/comment-choisir\\\/\",\"name\":\"Comment choisir ? - Ellistat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/comment-choisir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/comment-choisir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/doe1.png\",\"datePublished\":\"2026-08-12T14:58:48+00:00\",\"description\":\"D\u00e9crivez votre objectif, votre nombre de facteurs et votre budget d'essais : l'assistant Ellistat recommande le plan d'exp\u00e9riences adapt\u00e9 et explique pourquoi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/comment-choisir\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/comment-choisir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/comment-choisir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/doe1.png\",\"contentUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/doe1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/guide-dutilisateur\\\/comment-choisir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ellistat.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment choisir ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/#website\",\"url\":\"https:\\\/\\\/ellistat.com\\\/\",\"name\":\"Ellistat\",\"description\":\"La suite qualit\u00e9 de l&#039;industrie m\u00e9canique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ellistat.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come scegliere? - Ellistat","description":"Descrivi il tuo obiettivo, il numero di fattori e il budget a disposizione per gli esperimenti: l'assistente Ellistat ti consiglier\u00e0 il piano sperimentale pi\u00f9 adatto e ti spiegher\u00e0 il perch\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ellistat.com\/it\/guida-per-lutente\/come-scegliere\/","og_locale":"it_IT","og_type":"article","og_title":"Comment choisir ? - Ellistat","og_description":"D\u00e9crivez votre objectif, votre nombre de facteurs et votre budget d'essais : l'assistant Ellistat recommande le plan d'exp\u00e9riences adapt\u00e9 et explique pourquoi.","og_url":"https:\/\/ellistat.com\/it\/guida-per-lutente\/come-scegliere\/","og_site_name":"Ellistat","og_image":[{"width":644,"height":424,"url":"https:\/\/ellistat.com\/wp-content\/uploads\/doe1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ellistat.com\/guide-dutilisateur\/comment-choisir\/","url":"https:\/\/ellistat.com\/guide-dutilisateur\/comment-choisir\/","name":"Come scegliere? - Ellistat","isPartOf":{"@id":"https:\/\/ellistat.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ellistat.com\/guide-dutilisateur\/comment-choisir\/#primaryimage"},"image":{"@id":"https:\/\/ellistat.com\/guide-dutilisateur\/comment-choisir\/#primaryimage"},"thumbnailUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/doe1.png","datePublished":"2026-08-12T14:58:48+00:00","description":"Descrivi il tuo obiettivo, il numero di fattori e il budget a disposizione per gli esperimenti: l'assistente Ellistat ti consiglier\u00e0 il piano sperimentale pi\u00f9 adatto e ti spiegher\u00e0 il perch\u00e9.","breadcrumb":{"@id":"https:\/\/ellistat.com\/guide-dutilisateur\/comment-choisir\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ellistat.com\/guide-dutilisateur\/comment-choisir\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ellistat.com\/guide-dutilisateur\/comment-choisir\/#primaryimage","url":"https:\/\/ellistat.com\/wp-content\/uploads\/doe1.png","contentUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/doe1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/ellistat.com\/guide-dutilisateur\/comment-choisir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ellistat.com\/"},{"@type":"ListItem","position":2,"name":"Comment choisir ?"}]},{"@type":"WebSite","@id":"https:\/\/ellistat.com\/#website","url":"https:\/\/ellistat.com\/","name":"Ellistat","description":"La suite della qualit\u00e0 per l'industria meccanica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ellistat.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/guide-dutilisateur\/4649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/guide-dutilisateur"}],"about":[{"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/types\/guide-dutilisateur"}],"wp:attachment":[{"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/media?parent=4649"}],"wp:term":[{"taxonomy":"menu-guide-dutilisateur","embeddable":true,"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/menu-guide-dutilisateur?post=4649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}