{"id":2708,"date":"2024-10-15T17:05:11","date_gmt":"2024-10-15T15:05:11","guid":{"rendered":"https:\/\/ellistat.com\/?p=2708"},"modified":"2024-11-26T10:27:59","modified_gmt":"2024-11-26T09:27:59","slug":"spc-o-controllo-per-campionamento","status":"publish","type":"post","link":"https:\/\/ellistat.com\/it\/spc-ou-controle-par-echantillonnage\/","title":{"rendered":"SPC o controllo per campionamento"},"content":{"rendered":"<p>Quando si esegue un'ispezione di produzione, spesso si pone la questione del tipo di ispezione. Quale modulo utilizzare, quello SPC o quello IQC (Inspection by sampling)?<\/p>\n\n\n\n<p>Per rispondere correttamente a questa domanda, dobbiamo distinguere tra questi due tipi di controllo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CSP<\/h2>\n\n\n\n<p>Lo scopo dell'SPC \u00e8 monitorare un processo durante la produzione. La nozione di temporalit\u00e0 \u00e8 importante, poich\u00e9 i pezzi vengono prodotti in un ordine particolare e il diagramma di controllo viene utilizzato per fare un resoconto della linea di produzione. Inoltre, l'SPC consente di monitorare un processo in tempo reale, il che significa che qualsiasi deriva nel processo invier\u00e0 un avviso all'operatore in modo che possa reagire.<\/p>\n\n\n\n<p>La nozione di campionamento globale non \u00e8 particolarmente importante nell'SPC e ci concentreremo solo su..:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Campionamento a breve termine: per ogni campione vengono misurate 1, 3 o 5 parti per caratterizzare sia la centratura che la dispersione del processo al momento del campionamento.<\/li>\n\n\n\n<li>Il tempo tra due campionamenti: tra due campionamenti, la macchina potrebbe aver subito una deriva, quindi \u00e8 importante mantenere una frequenza di campionamento che consenta di rilevare la deriva con sufficiente anticipo. In SPC, la frequenza di campionamento NON dipende dalle dimensioni del lotto, ma solo dalla deriva del processo.<\/li>\n<\/ul>\n\n\n\n<p>Con l'SPC \u00e8 possibile calcolare una percentuale di errore dai risultati della misurazione.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CQI (Ispezione per campionamento)<\/h2>\n\n\n\n<p>Lo scopo del campionamento \u00e8 determinare se il lotto prodotto soddisfa i requisiti di qualit\u00e0 stabiliti. Viene quindi effettuato POSTERIORI. Nel CQI, la nozione di temporalit\u00e0 non \u00e8 importante. I pezzi sono stati tutti prodotti, quindi si preleva un campione indipendentemente dall'ordine di produzione.<\/p>\n\n\n\n<p>Il concetto di campionamento globale \u00e8 fondamentale nel CQI. Infatti, il controllo per campionamento consiste nel misurare un numero specifico di campioni per convalidare o rifiutare il lotto. Il numero di campioni dipende da:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La dimensione del lotto<\/li>\n\n\n\n<li>Il tipo di ispezione, cio\u00e8 l'AQL (Acceptable Quality Level) e la gravit\u00e0 dell'ispezione.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Come ottenere il meglio dei due mondi<\/h2>\n\n\n\n<p>A volte si vuole essere in grado di accettare o rifiutare un lotto che \u00e8 in produzione. \u00c8 quindi necessario garantire un campionamento globale (per poter convalidare il lotto) di un lotto che \u00e8 a sua volta in fase di produzione.<\/p>\n\n\n\n<p>A tal fine, le regole dell'SPC classico devono essere applicate finch\u00e9 il lotto \u00e8 in produzione. Il campionamento in questa fase non dipende dalle dimensioni del lotto e consente di individuare eventuali derive del processo.<\/p>\n\n\n\n<p>Una volta prodotto il lotto, tutte le misure vengono trasferite al modulo IQC. Se il numero di misurazioni \u00e8 sufficiente, possiamo convalidare direttamente la produzione o meno. In caso contrario, \u00e8 sufficiente misurare il numero di prodotti mancanti per poter effettuare controlli a campione direttamente in produzione.<\/p>","protected":false},"excerpt":{"rendered":"<p>Lorsque l&rsquo;on r\u00e9alise un contr\u00f4le en production se pose souvent la question du type de contr\u00f4le. Quel module dois-je utiliser, le module SPC ou IQC (Contr\u00f4le par \u00e9chantillonnage). Pour y r\u00e9pondre correctement, il faut bien distinguer la diff\u00e9rence entre ces deux types de contr\u00f4les. SPC Le SPC a pour objectif de suivre un proc\u00e9d\u00e9 en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2934,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,4],"tags":[],"class_list":["post-2708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iqc","category-spc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SPC ou contr\u00f4le par \u00e9chantillonnage - Ellistat<\/title>\n<meta name=\"description\" content=\"Lorsque l&#039;on r\u00e9alise un contr\u00f4le en production se pose souvent la question du type de contr\u00f4le. Quel module dois-je utiliser SPC ou IQC ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ellistat.com\/it\/spc-o-controllo-per-campionamento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SPC ou contr\u00f4le par \u00e9chantillonnage - Ellistat\" \/>\n<meta property=\"og:description\" content=\"Lorsque l&#039;on r\u00e9alise un contr\u00f4le en production se pose souvent la question du type de contr\u00f4le. Quel module dois-je utiliser SPC ou IQC ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ellistat.com\/it\/spc-o-controllo-per-campionamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Ellistat\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-15T15:05:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-26T09:27:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ellistat.com\/wp-content\/uploads\/SPC-vs-IQC-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"851\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Davy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/\"},\"author\":{\"name\":\"Davy\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/#\\\/schema\\\/person\\\/e2a04a9eb45bae5d885b534cbf70df8d\"},\"headline\":\"SPC ou contr\u00f4le par \u00e9chantillonnage\",\"datePublished\":\"2024-10-15T15:05:11+00:00\",\"dateModified\":\"2024-11-26T09:27:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/\"},\"wordCount\":557,\"image\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/SPC-vs-IQC-2.png\",\"articleSection\":[\"IQC\",\"SPC\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/\",\"url\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/\",\"name\":\"SPC ou contr\u00f4le par \u00e9chantillonnage - Ellistat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/SPC-vs-IQC-2.png\",\"datePublished\":\"2024-10-15T15:05:11+00:00\",\"dateModified\":\"2024-11-26T09:27:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/#\\\/schema\\\/person\\\/e2a04a9eb45bae5d885b534cbf70df8d\"},\"description\":\"Lorsque l'on r\u00e9alise un contr\u00f4le en production se pose souvent la question du type de contr\u00f4le. Quel module dois-je utiliser SPC ou IQC ?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/SPC-vs-IQC-2.png\",\"contentUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/uploads\\\/SPC-vs-IQC-2.png\",\"width\":851,\"height\":315,\"caption\":\"SPC ou contr\u00f4le par \u00e9chantillonnage ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/spc-ou-controle-par-echantillonnage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ellistat.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IQC\",\"item\":\"https:\\\/\\\/ellistat.com\\\/category\\\/iqc\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SPC ou contr\u00f4le par \u00e9chantillonnage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/#website\",\"url\":\"https:\\\/\\\/ellistat.com\\\/\",\"name\":\"Ellistat\",\"description\":\"La suite qualit\u00e9 de l&#039;industrie m\u00e9canique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ellistat.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/#\\\/schema\\\/person\\\/e2a04a9eb45bae5d885b534cbf70df8d\",\"name\":\"Davy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/litespeed\\\/avatar\\\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658\",\"url\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/litespeed\\\/avatar\\\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658\",\"contentUrl\":\"https:\\\/\\\/ellistat.com\\\/wp-content\\\/litespeed\\\/avatar\\\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658\",\"caption\":\"Davy\"},\"sameAs\":[\"https:\\\/\\\/ellistat.com\"],\"url\":\"https:\\\/\\\/ellistat.com\\\/it\\\/author\\\/elliadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SPC o controllo per campionamento - Ellistat","description":"Quando si effettua un'ispezione di produzione, spesso si pone la questione del tipo di ispezione. Quale modulo utilizzare, SPC o IQC?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ellistat.com\/it\/spc-o-controllo-per-campionamento\/","og_locale":"it_IT","og_type":"article","og_title":"SPC ou contr\u00f4le par \u00e9chantillonnage - Ellistat","og_description":"Lorsque l'on r\u00e9alise un contr\u00f4le en production se pose souvent la question du type de contr\u00f4le. Quel module dois-je utiliser SPC ou IQC ?","og_url":"https:\/\/ellistat.com\/it\/spc-o-controllo-per-campionamento\/","og_site_name":"Ellistat","article_published_time":"2024-10-15T15:05:11+00:00","article_modified_time":"2024-11-26T09:27:59+00:00","og_image":[{"width":851,"height":315,"url":"https:\/\/ellistat.com\/wp-content\/uploads\/SPC-vs-IQC-2.png","type":"image\/png"}],"author":"Davy","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Davy","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/#article","isPartOf":{"@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/"},"author":{"name":"Davy","@id":"https:\/\/ellistat.com\/#\/schema\/person\/e2a04a9eb45bae5d885b534cbf70df8d"},"headline":"SPC ou contr\u00f4le par \u00e9chantillonnage","datePublished":"2024-10-15T15:05:11+00:00","dateModified":"2024-11-26T09:27:59+00:00","mainEntityOfPage":{"@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/"},"wordCount":557,"image":{"@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/#primaryimage"},"thumbnailUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/SPC-vs-IQC-2.png","articleSection":["IQC","SPC"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/","url":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/","name":"SPC o controllo per campionamento - Ellistat","isPartOf":{"@id":"https:\/\/ellistat.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/#primaryimage"},"image":{"@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/#primaryimage"},"thumbnailUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/SPC-vs-IQC-2.png","datePublished":"2024-10-15T15:05:11+00:00","dateModified":"2024-11-26T09:27:59+00:00","author":{"@id":"https:\/\/ellistat.com\/#\/schema\/person\/e2a04a9eb45bae5d885b534cbf70df8d"},"description":"Quando si effettua un'ispezione di produzione, spesso si pone la questione del tipo di ispezione. Quale modulo utilizzare, SPC o IQC?","breadcrumb":{"@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/#primaryimage","url":"https:\/\/ellistat.com\/wp-content\/uploads\/SPC-vs-IQC-2.png","contentUrl":"https:\/\/ellistat.com\/wp-content\/uploads\/SPC-vs-IQC-2.png","width":851,"height":315,"caption":"SPC ou contr\u00f4le par \u00e9chantillonnage ?"},{"@type":"BreadcrumbList","@id":"https:\/\/ellistat.com\/spc-ou-controle-par-echantillonnage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ellistat.com\/"},{"@type":"ListItem","position":2,"name":"IQC","item":"https:\/\/ellistat.com\/category\/iqc\/"},{"@type":"ListItem","position":3,"name":"SPC ou contr\u00f4le par \u00e9chantillonnage"}]},{"@type":"WebSite","@id":"https:\/\/ellistat.com\/#website","url":"https:\/\/ellistat.com\/","name":"Ellistat","description":"La suite della qualit\u00e0 per l'industria meccanica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ellistat.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/ellistat.com\/#\/schema\/person\/e2a04a9eb45bae5d885b534cbf70df8d","name":"Davy","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ellistat.com\/wp-content\/litespeed\/avatar\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658","url":"https:\/\/ellistat.com\/wp-content\/litespeed\/avatar\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658","contentUrl":"https:\/\/ellistat.com\/wp-content\/litespeed\/avatar\/e2d1fff799059e0c9b9f4f3451274ada.jpg?ver=1778088658","caption":"Davy"},"sameAs":["https:\/\/ellistat.com"],"url":"https:\/\/ellistat.com\/it\/author\/elliadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/posts\/2708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/comments?post=2708"}],"version-history":[{"count":2,"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/posts\/2708\/revisions"}],"predecessor-version":[{"id":2717,"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/posts\/2708\/revisions\/2717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/media\/2934"}],"wp:attachment":[{"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/media?parent=2708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/categories?post=2708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellistat.com\/it\/wp-json\/wp\/v2\/tags?post=2708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}